{"id":4211,"date":"2022-12-29T17:50:29","date_gmt":"2022-12-29T16:50:29","guid":{"rendered":"https:\/\/klimaneutral2035.de\/?post_type=tribe_events&#038;p=4211"},"modified":"2023-01-03T12:47:19","modified_gmt":"2023-01-03T11:47:19","slug":"klimagesund-essen-vortrag-austausch-in-unterbiberg","status":"publish","type":"tribe_events","link":"https:\/\/klimaneutral2035.de\/en\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/","title":{"rendered":"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg"},"content":{"rendered":"<p>Wir laden Sie herzlich zu unserem\u00a0<strong>Themenabend \u201eKlimagesund Essen\u201c\u00a0<\/strong>am\u00a0<strong>Montag 15. Mai 2023 von 19:00 \u2013 ca. 21:00 Uhr\u00a0<\/strong>ein und freuen uns auf Ihre Anmeldung &amp; Teilnahme. Es erwartet Sie ein 20-min\u00fctiger Vortrag mit anschlie\u00dfendem Austausch in gem\u00fctlicher Runde sowie klimafreundliche H\u00e4ppchen :).<\/p>\n<p>Essen ist viel mehr als nur Kalorienaufnahme. Ein gutes Essen macht uns zufrieden und gl\u00fccklich. Immer mehr Menschen haben verstanden, dass (zu) billige Lebensmittel, vor allem billiges Fleisch, uns alle teuer zu stehen kommen. Sie gehen einher mit einer rasant fortschreitenden Klimakrise, der Zerst\u00f6rung unserer Umwelt und unseren nat\u00fcrlichen Lebensgrundlagen, Artensterben, verschmutztem Wasser und nicht zuletzt unserer Gesundheit.<\/p>\n<p>Gute Lebensmittel zu bezahlbaren Preisen f\u00fcr das gute Leben f\u00fcr alle. Wie k\u00f6nnen wir das erreichen? Was muss sich dazu ver\u00e4ndern? Was kann ich als Einzelne\/r dazu beitragen? Dazu wollen wir aufkl\u00e4ren, unterschiedliche Optionen vorstellen und mit Ihnen gemeinsam diskutieren.<\/p>\n<p><strong>Veranstalter:<\/strong>\u00a0Neubiberg for Future in Kooperation mit der\u00a0Initiative Neubiberg\u00a0<a href=\"https:\/\/klimaneutral2035.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Klimaneutral 2035<\/a>\u00a0samt\u00a0freundlicher Unterst\u00fctzung des Sachbereichs Unterbiberg im Pfarrverband Perlach.<br \/>\n<strong>Referentin:<\/strong>\u00a0Beatrix Fuchs, Greenpeace<br \/>\n<strong>Kostenfrei, Spenden willkommen<br \/>\nVeranstaltungsort\u00a0<\/strong>Pfarrheim St. Georg in Unterbiberg<\/p>\n<p><strong>Zur besseren Planung bitten wir Sie um eine Anmeldung \u2013<br \/>\n<\/strong><noscript class=\"ninja-forms-noscript-message\">\n\tNotice: JavaScript is required for this content.<\/noscript>\n<div id=\"nf-form-13-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-13\" aria-describedby=\"nf-form-errors-13\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='13';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"Klimagesund essen - Mai 2023\",\"created_at\":\"2022-12-30 19:52:09\",\"form_title\":\"Event Registration\",\"default_label_pos\":\"above\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"0\",\"key\":\"\",\"wrapper_class\":\"\",\"element_class\":\"\",\"add_submit\":\"0\",\"not_logged_in_msg\":\"\",\"sub_limit_number\":\"\",\"sub_limit_msg\":\"\",\"calculations\":[],\"formContentData\":[\"hr\",\"vorname_1637523872268\",\"nachname_1637523880777\",\"email\",\"wohnort_1637523961621\",\"hr_2\",\"ich_unterstuetze_die_ziele_von_klimaneutral_2035_1638800198877\",\"unsere_ziele_1638800981922\",\"ich_moechte_neuigkeiten_zur_initiative_erfahren_1637524217790\",\"ich_akzeptiere_die_datenschutzbestimmungen_1638800861779\",\"html_1638802586515\",\"registrieren_1637524243650\"],\"currency\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"repeatable_fieldsets\":\"\",\"changeEmailErrorMsg\":\"Please enter a valid email address!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"These fields must match!\",\"fieldNumberNumMinError\":\"Number Min Error\",\"fieldNumberNumMaxError\":\"Number Max Error\",\"fieldNumberIncrementBy\":\"Please increment by \",\"formErrorsCorrectErrors\":\"Please correct errors before submitting this form.\",\"validateRequiredField\":\"This is a required field.\",\"honeypotHoneypotError\":\"Honeypot Error\",\"fieldsMarkedRequired\":\"Fields marked with an <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> are required\",\"drawerDisabled\":false,\"allow_public_link\":0,\"embed_form\":\"\",\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Insert Link\",\"fieldTextareaRTEInsertMedia\":\"Insert Media\",\"fieldTextareaRTESelectAFile\":\"Select a file\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Dismiss\",\"insertLink\":\"Insert Link\",\"formHoneypot\":\"If you are a human seeing this field, please leave it empty.\",\"fileUploadOldCodeFileUploadInProgress\":\"File Upload in Progress.\",\"fileUploadOldCodeFileUpload\":\"FILE UPLOAD\",\"currencySymbol\":\"&euro;\",\"thousands_sep\":\",\",\"decimal_point\":\".\",\"siteLocale\":\"en_US\",\"dateFormat\":\"d\\\/m\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"of\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":2,\"idAttribute\":\"id\",\"label\":\"Divider\",\"key\":\"hr\",\"type\":\"hr\",\"created_at\":\"2016-08-28 16:16:05\",\"container_class\":\"\",\"element_class\":\"\",\"field_label\":\"Divider\",\"field_key\":\"hr\",\"drawerDisabled\":\"\",\"id\":147,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Vorname\",\"key\":\"vorname_1637523872268\",\"type\":\"firstname\",\"created_at\":\"2016-08-28 16:16:05\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"one-half first\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"\",\"field_label\":\"Vorname\",\"field_key\":\"vorname_1637523872268\",\"custom_name_attribute\":\"fname\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"id\":148,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"Nachname\",\"key\":\"nachname_1637523880777\",\"type\":\"lastname\",\"created_at\":\"2016-08-28 16:16:05\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"one-half\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"\",\"field_label\":\"Nachname\",\"field_key\":\"nachname_1637523880777\",\"custom_name_attribute\":\"lname\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"id\":149,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"lastname\",\"element_templates\":[\"lastname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"label\":\"Email\",\"key\":\"email\",\"type\":\"email\",\"created_at\":\"2016-08-28 16:16:05\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"one-half first\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"\",\"field_label\":\"Email\",\"field_key\":\"email\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":\"\",\"id\":150,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"label\":\"Wohnort\",\"key\":\"wohnort_1637523961621\",\"type\":\"listselect\",\"created_at\":\"2016-08-28 16:16:05\",\"label_pos\":\"above\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"\",\"field_label\":\"Wohnort\",\"field_key\":\"wohnort_1637523961621\",\"drawerDisabled\":\"\",\"options\":[{\"errors\":[],\"max_options\":\"0\",\"order\":\"0\",\"new\":\"\",\"options\":[],\"label\":\"Neubiberg\",\"value\":\"neubiberg\",\"calc\":\"\",\"selected\":\"0\",\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":\"0\",\"label\":\"Unterbiberg\",\"value\":\"unterbiberg\",\"calc\":\"\",\"selected\":\"0\",\"order\":\"1\",\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}},{\"errors\":[],\"max_options\":\"0\",\"label\":\"Anderswo\",\"value\":\"anderswo\",\"calc\":\"\",\"selected\":\"0\",\"order\":\"2\",\"settingModel\":{\"settings\":false,\"hide_merge_tags\":false,\"error\":false,\"name\":\"options\",\"type\":\"option-repeater\",\"label\":\"Optionen <a href=\\\"#\\\" class=\\\"nf-add-new\\\">Erstellen<\\\/a> <a href=\\\"#\\\" class=\\\"extra nf-open-import-tooltip\\\"><i class=\\\"fa fa-sign-in\\\" aria-hidden=\\\"true\\\"><\\\/i> Importieren<\\\/a>\",\"width\":\"full\",\"group\":\"\",\"value\":[{\"label\":\"Eins\",\"value\":\"eins\",\"calc\":\"\",\"selected\":0,\"order\":0},{\"label\":\"Zwei\",\"value\":\"zwei\",\"calc\":\"\",\"selected\":0,\"order\":1},{\"label\":\"Drei\",\"value\":\"drei\",\"calc\":\"\",\"selected\":0,\"order\":2}],\"columns\":{\"label\":{\"header\":\"Beschriftung\",\"default\":\"\"},\"value\":{\"header\":\"Wert\",\"default\":\"\"},\"calc\":{\"header\":\"Berechneter Wert\",\"default\":\"\"},\"selected\":{\"header\":\"<span class=\\\"dashicons dashicons-yes\\\"><\\\/span>\",\"default\":0}}}}],\"id\":151,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"list\",\"element_templates\":[\"listselect\",\"input\"],\"old_classname\":\"list-select\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"Divider\",\"key\":\"hr_2\",\"type\":\"hr\",\"created_at\":\"2016-08-28 16:16:05\",\"container_class\":\"\",\"element_class\":\"\",\"field_label\":\"Divider\",\"field_key\":\"hr_2\",\"drawerDisabled\":\"\",\"id\":152,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"hr\",\"element_templates\":[\"hr\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"type\":\"checkbox\",\"label\":\"Ich unterst\\u00fctze die Ziele von Klimaneutral 2035:\",\"key\":\"ich_unterstuetze_die_ziele_von_klimaneutral_2035_1638800198877\",\"label_pos\":\"right\",\"required\":0,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"<br>\",\"default_value\":\"unchecked\",\"checked_value\":\"Ausgew\\u00e4hlt\",\"unchecked_value\":\"Nicht ausgew\\u00e4hlt\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Ich unterst\\u00fctze die Ziele von Klimaneutral 2035:\",\"field_key\":\"ich_unterstuetze_die_ziele_von_klimaneutral_2035_1638800198877\",\"id\":154,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"label\":\"Unsere Ziele\",\"type\":\"html\",\"default\":\"<a href=\\\"https:\\\/\\\/klimaneutral2035.de\\\/unsere-ziele\\\/\\\" target=\\\"_blank\\\" style=\\\"display: block; margin: 0px 0 0 30px;\\\">Unsere Ziele<\\\/a>\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"unsere_ziele_1638800981922\",\"drawerDisabled\":\"\",\"field_label\":\"Unsere Ziele\",\"field_key\":\"unsere_ziele_1638800981922\",\"id\":157,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<a href=\\\"https:\\\/\\\/klimaneutral2035.de\\\/unsere-ziele\\\/\\\" target=\\\"_blank\\\" style=\\\"display: block; margin: 0px 0 0 30px;\\\">Unsere Ziele<\\\/a>\",\"label_pos\":\"above\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"type\":\"checkbox\",\"label\":\"Ich m\\u00f6chte Neuigkeiten zur Initiative erfahren!\",\"key\":\"ich_moechte_neuigkeiten_zur_initiative_erfahren_1637524217790\",\"label_pos\":\"right\",\"required\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Ausgew\\u00e4hlt\",\"unchecked_value\":\"Nicht ausgew\\u00e4hlt\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Ich m\\u00f6chte Neuigkeiten zur Initiative erfahren!\",\"field_key\":\"ich_moechte_neuigkeiten_zur_initiative_erfahren_1637524217790\",\"id\":155,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"type\":\"checkbox\",\"label\":\"Ich akzeptiere die Datenschutzbestimmungen\",\"key\":\"ich_akzeptiere_die_datenschutzbestimmungen_1638800861779\",\"label_pos\":\"right\",\"required\":1,\"container_class\":\"\",\"element_class\":\"\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"desc_text\":\"\",\"default_value\":\"unchecked\",\"checked_value\":\"Ausgew\\u00e4hlt\",\"unchecked_value\":\"Nicht ausgew\\u00e4hlt\",\"checked_calc_value\":\"\",\"unchecked_calc_value\":\"\",\"drawerDisabled\":\"\",\"field_label\":\"Ich akzeptiere die Datenschutzbestimmungen\",\"field_key\":\"ich_akzeptiere_die_datenschutzbestimmungen_1638800861779\",\"id\":156,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"parentType\":\"checkbox\",\"element_templates\":[\"checkbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":12,\"idAttribute\":\"id\",\"label\":\"Unsere Ziele Copy\",\"type\":\"html\",\"default\":\"<span style=\\\"display: block; margin: 0px 0 0 30px; font-size: 0.7em;\\\">Ihre Daten werden an keiner Stelle \\u00f6ffentlich gemacht! Datenschutz ist uns wichtig. Alle Informationen dazu finden Sie in unseren <a href=\\\"https:\\\/\\\/klimaneutral2035.de\\\/privacy-policy\\\/\\\" target=\\\"_blank\\\">Datenschutzbestimmungen<\\\/a>.<\\\/span>\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"html_1638802586515\",\"drawerDisabled\":\"\",\"field_label\":\"Unsere Ziele Copy\",\"field_key\":\"html_1638802586515\",\"id\":158,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<span style=\\\"display: block; margin: 0px 0 0 30px; font-size: 0.7em;\\\">Ihre Daten werden an keiner Stelle \\u00f6ffentlich gemacht! Datenschutz ist uns wichtig. Alle Informationen dazu finden Sie in unseren <a href=\\\"https:\\\/\\\/klimaneutral2035.de\\\/privacy-policy\\\/\\\" target=\\\"_blank\\\">Datenschutzbestimmungen<\\\/a>.<\\\/span>\",\"label_pos\":\"above\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":13,\"idAttribute\":\"id\",\"label\":\"Registrieren\",\"key\":\"registrieren_1637524243650\",\"type\":\"submit\",\"created_at\":\"2016-08-28 16:16:05\",\"processing_label\":\"Processing\",\"container_class\":\"\",\"element_class\":\"\",\"field_label\":\"Registrieren\",\"field_key\":\"registrieren_1637524243650\",\"drawerDisabled\":\"\",\"id\":153,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        \n<p><strong>Hinweis!:<\/strong> Aus Gr\u00fcnden der \u00dcbersichtlichkeit werden Ihre Anmeldedaten an Neubiberg for Future weitergegeben. Mit Ihrer Anmeldung und Eingabe Ihrer Daten in unser Formular erkl\u00e4ren Sie sich mit dieser Weitergabe einverstanden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir laden Sie herzlich zu unserem\u00a0Themenabend \u201eKlimagesund Essen\u201c\u00a0am\u00a0Montag 15. Mai 2023 von 19:00 \u2013 ca. 21:00 Uhr\u00a0ein und freuen uns auf Ihre Anmeldung &amp; Teilnahme. Es erwartet Sie ein 20-min\u00fctiger Vortrag mit anschlie\u00dfendem Austausch in gem\u00fctlicher Runde sowie klimafreundliche H\u00e4ppchen :). Essen ist viel mehr als nur Kalorienaufnahme. Ein gutes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-4211","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klimaneutral2035.de\/en\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035\" \/>\n<meta property=\"og:description\" content=\"Wir laden Sie herzlich zu unserem\u00a0Themenabend \u201eKlimagesund Essen\u201c\u00a0am\u00a0Montag 15. Mai 2023 von 19:00 \u2013 ca. 21:00 Uhr\u00a0ein und freuen uns auf Ihre Anmeldung &amp; Teilnahme. Es erwartet Sie ein 20-min\u00fctiger Vortrag mit anschlie\u00dfendem Austausch in gem\u00fctlicher Runde sowie klimafreundliche H\u00e4ppchen :). Essen ist viel mehr als nur Kalorienaufnahme. Ein gutes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klimaneutral2035.de\/en\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Klimaneutral 2035\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Klimaneutral-2035\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-03T11:47:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Klimaneutral35\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/event\\\/klimagesund-essen-vortrag-austausch-in-unterbiberg\\\/\",\"url\":\"https:\\\/\\\/klimaneutral2035.de\\\/event\\\/klimagesund-essen-vortrag-austausch-in-unterbiberg\\\/\",\"name\":\"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#website\"},\"datePublished\":\"2022-12-29T16:50:29+00:00\",\"dateModified\":\"2023-01-03T11:47:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/event\\\/klimagesund-essen-vortrag-austausch-in-unterbiberg\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/klimaneutral2035.de\\\/event\\\/klimagesund-essen-vortrag-austausch-in-unterbiberg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/event\\\/klimagesund-essen-vortrag-austausch-in-unterbiberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/klimaneutral2035.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/klimaneutral2035.de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#website\",\"url\":\"https:\\\/\\\/klimaneutral2035.de\\\/\",\"name\":\"Klimaneutral 2035\",\"description\":\"Eine Initiative f\u00fcr Neubiberg\",\"publisher\":{\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/klimaneutral2035.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#organization\",\"name\":\"Klimaneutral 2035\",\"url\":\"https:\\\/\\\/klimaneutral2035.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/klimaneutral2035.de\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/klimaneutral2035.de\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Klimaneutral 2035\"},\"image\":{\"@id\":\"https:\\\/\\\/klimaneutral2035.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Klimaneutral-2035\",\"https:\\\/\\\/x.com\\\/Klimaneutral35\",\"https:\\\/\\\/www.instagram.com\\\/klimaneutral_2035\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klimaneutral2035.de\/en\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/","og_locale":"en_US","og_type":"article","og_title":"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035","og_description":"Wir laden Sie herzlich zu unserem\u00a0Themenabend \u201eKlimagesund Essen\u201c\u00a0am\u00a0Montag 15. Mai 2023 von 19:00 \u2013 ca. 21:00 Uhr\u00a0ein und freuen uns auf Ihre Anmeldung &amp; Teilnahme. Es erwartet Sie ein 20-min\u00fctiger Vortrag mit anschlie\u00dfendem Austausch in gem\u00fctlicher Runde sowie klimafreundliche H\u00e4ppchen :). Essen ist viel mehr als nur Kalorienaufnahme. Ein gutes [&hellip;]","og_url":"https:\/\/klimaneutral2035.de\/en\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/","og_site_name":"Klimaneutral 2035","article_publisher":"https:\/\/www.facebook.com\/Klimaneutral-2035","article_modified_time":"2023-01-03T11:47:19+00:00","twitter_card":"summary_large_image","twitter_site":"@Klimaneutral35","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klimaneutral2035.de\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/","url":"https:\/\/klimaneutral2035.de\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/","name":"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg - Klimaneutral 2035","isPartOf":{"@id":"https:\/\/klimaneutral2035.de\/#website"},"datePublished":"2022-12-29T16:50:29+00:00","dateModified":"2023-01-03T11:47:19+00:00","breadcrumb":{"@id":"https:\/\/klimaneutral2035.de\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klimaneutral2035.de\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/klimaneutral2035.de\/event\/klimagesund-essen-vortrag-austausch-in-unterbiberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/klimaneutral2035.de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/klimaneutral2035.de\/events\/"},{"@type":"ListItem","position":3,"name":"Klimagesund Essen \u2013 Vortrag &amp; Austausch in Unterbiberg"}]},{"@type":"WebSite","@id":"https:\/\/klimaneutral2035.de\/#website","url":"https:\/\/klimaneutral2035.de\/","name":"Klimaneutral 2035","description":"Eine Initiative f\u00fcr Neubiberg","publisher":{"@id":"https:\/\/klimaneutral2035.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klimaneutral2035.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/klimaneutral2035.de\/#organization","name":"Klimaneutral 2035","url":"https:\/\/klimaneutral2035.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/klimaneutral2035.de\/#\/schema\/logo\/image\/","url":"https:\/\/klimaneutral2035.de\/wp-content\/uploads\/cropped-favicon.png","contentUrl":"https:\/\/klimaneutral2035.de\/wp-content\/uploads\/cropped-favicon.png","width":512,"height":512,"caption":"Klimaneutral 2035"},"image":{"@id":"https:\/\/klimaneutral2035.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Klimaneutral-2035","https:\/\/x.com\/Klimaneutral35","https:\/\/www.instagram.com\/klimaneutral_2035"]}]}},"_links":{"self":[{"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tribe_events\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":4,"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tribe_events\/4211\/revisions"}],"predecessor-version":[{"id":4261,"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tribe_events\/4211\/revisions\/4261"}],"wp:attachment":[{"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/media?parent=4211"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tags?post=4211"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/klimaneutral2035.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}